{"id":48379,"date":"2020-12-11T13:14:08","date_gmt":"2020-12-11T12:14:08","guid":{"rendered":"https:\/\/eriacomponentes.es\/o-que-sao-mecanismos-electricos\/"},"modified":"2020-12-11T13:14:08","modified_gmt":"2020-12-11T12:14:08","slug":"o-que-sao-mecanismos-electricos","status":"publish","type":"post","link":"https:\/\/eriacomponentes.es\/pt-pt\/o-que-sao-mecanismos-electricos\/","title":{"rendered":"O que s\u00e3o mecanismos el\u00e9ctricos?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Os <strong>mecanismos el\u00e9ctricos<\/strong>  s\u00e3o um dos componentes essenciais em todos os tipos de casas e a sua escolha depende de muitos factores: o estilo decorativo da casa ou do escrit\u00f3rio, o desenho do mecanismo, o seu pre\u00e7o ou a utilidade dos interruptores el\u00e9ctricos s\u00e3o alguns dos factores determinantes a ter em conta, fazendo a distin\u00e7\u00e3o entre  <strong>diferentes tipos de mecanismos<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-14212 size-medium\" title=\"Mecanismos el\u00e9ctricos do estilo Delta\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/mecanismos-style-300x300-3-300x300.jpg\" alt=\"Mecanismos el\u00e9ctricos do estilo Delta\" width=\"300\" height=\"300\"><\/p>\n<p>Mas o que queremos dizer quando falamos de mecanismos el\u00e9ctricos? O  <strong>dispositivos el\u00e9ctricos<\/strong>  s\u00e3o, por um lado,  <strong>elementos de manobras<\/strong>ou seja, dispositivos destinados a permitir ou interromper o fluxo de corrente quando operados por utilizadores:  <em>interruptores, comutadores, interruptores crossover, bot\u00f5es de press\u00e3o<\/em>&#8230; Por outro lado, eles s\u00e3o<strong>  bases de tomadas  <\/strong>ou dispositivos cuja tarefa \u00e9 ligar a alimenta\u00e7\u00e3o el\u00e9ctrica aos receptores atrav\u00e9s da tomada do receptor.<\/p>\n<p>Actualmente, podemos encontrar um grande n\u00famero de <strong>modelos de mecanismos el\u00e9ctricos <\/strong>no mercado. Podemos distinguir duas variedades de acordo com a forma como s\u00e3o montadas: <em>de montagem embutida ou de superf\u00edcie<\/em>.<\/p>\n<p>Na <a href=\"https:\/\/eriacomponentes.es\/\">Eria Componentes El\u00e9ctricos<\/a> temos uma grande variedade de <strong>mecanismos e componentes<\/strong> necess\u00e1rios para a sua instala\u00e7\u00e3o a pre\u00e7os muito competitivos e atractivos para indiv\u00edduos e profissionais. S\u00e3o mostrados abaixo:<\/p>\n<h2>Adaptadores<\/h2>\n<p>Os <strong>adaptadores<\/strong> facilitam a <strong>instala\u00e7\u00e3o dos mecanismos<\/strong> e s\u00e3o portanto recomendados tanto para novos projectos de constru\u00e7\u00e3o como de renova\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/eriacomponentes.es\/comprar\/adaptador-toma-rj45-rj11\/<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, os <a href=\"https:\/\/eriacomponentes.es\/comprar-online\/mecanismos\/bjc\/bjc-mec-18-bjc\/\">nossos adaptadores<\/a> s\u00e3o concebidos para que possa incorporar os <strong>elementos necess\u00e1rios<\/strong> para cada tomada.<\/p>\n<p><a href=\"https:\/\/eriacomponentes.es\/comprar\/tapa-toma-r-tv-sat-serie-iris-blanco\/\"><img decoding=\"async\" class=\"alignnone wp-image-14213 size-medium\" title=\"mecanismos el\u00e9ctricos cobertura da tomada de \u00edris\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tapa-toma-r-tv-sat-serie-iris-blanco-300x300-1-300x300.jpg\" alt=\"mecanismos el\u00e9ctricos cobertura da tomada de \u00edris\" width=\"300\" height=\"300\"><\/a><a href=\"https:\/\/eriacomponentes.es\/comprar\/tecla-pulsador-timbre-serie-iris-blanco\/\"><img decoding=\"async\" class=\"alignnone wp-image-14215\" title=\"campainha com mecanismo el\u00e9ctrico de bot\u00e3o de press\u00e3o\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-timbre-serie-iris-blanco-300x300-1-300x300.jpg\" alt=\"campainha com mecanismo el\u00e9ctrico de bot\u00e3o de press\u00e3o\" width=\"307\" height=\"307\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-timbre-serie-iris-blanco-300x300-1.jpg 300w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-timbre-serie-iris-blanco-300x300-1-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-timbre-serie-iris-blanco-300x300-1-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-timbre-serie-iris-blanco-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/a><\/p>\n<h2>Bot\u00f5es de press\u00e3o<\/h2>\n<p>Os<strong> bot\u00f5es de press\u00e3o<\/strong> s\u00e3o dispositivos destinados a permitir ou interromper o fluxo de corrente quando operados por utilizadores. Na <strong>Eria Componentes<\/strong> temos uma vasta gama de bot\u00f5es de press\u00e3o, tais como o <a href=\"https:\/\/eriacomponentes.es\/comprar\/pulsador-serie-iris-blanco\/\">bot\u00e3o Iris White Series Pushbutton<\/a>. Aqui est\u00e3o as suas caracter\u00edsticas<\/p>\n<ul>\n<li>  O espa\u00e7o interior das <strong>caixas de montagem embutida<\/strong> \u00e9 grande e manej\u00e1vel.<\/li>\n<li>  O tamanho menor do mecanismo significa que o interior da caixa embutida pode ser utilizado em todo o seu potencial.<\/li>\n<li>  Os mecanismos de quebra t\u00eam uma <strong>resist\u00eancia de 16A<\/strong>.<\/li>\n<li>  Molduras de qualidade sem \u00e2ngulos agressivos para um ajuste perfeito das molduras.<\/li>\n<li>  Marca\u00e7\u00f5es de posi\u00e7\u00e3o nas estantes para facilitar a instala\u00e7\u00e3o.<\/li>\n<li> <strong>Grampos autom\u00e1ticos<\/strong> para uma instala\u00e7\u00e3o mais r\u00e1pida.<\/li>\n<li>  Janelas de ventila\u00e7\u00e3o que impedem os contactos de aquecer.<\/li>\n<\/ul>\n<p>https:\/\/eriacomponentes.es\/comprar\/pulsador-serie-iris-blanco\/<\/p>\n<h2>Chaves<\/h2>\n<p>As<strong> chaves<\/strong> s\u00e3o os elementos de design dos <strong>adaptadores<\/strong>, ou seja, os elementos que d\u00e3o vida \u00e0 parede da sua casa, casa, escrit\u00f3rio ou empresa. Temos v\u00e1rios modelos, tais como as <strong>Double Keys with Led Lighting<\/strong>, ideais para comunidades, port\u00f5es e escrit\u00f3rios, ou as <a href=\"https:\/\/eriacomponentes.es\/comprar-online\/mecanismos\/bjc\/bjc-iris\/\">White Frame Keys<\/a> para uma decora\u00e7\u00e3o elegante.<\/p>\n<p>Pode encontrar a que melhor se adapta \u00e0s suas necessidades na nossa <strong>loja online de mecanismos el\u00e9ctricos<\/strong>.<\/p>\n<h2>         <a href=\"https:\/\/eriacomponentes.es\/comprar\/senalizador-interruptores-luz-pulsador\/\"><img decoding=\"async\" class=\"alignnone wp-image-14216 size-full\" title=\"mecanismos el\u00e9ctricos Chaves sinalizadoras\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/a.jpg\" alt=\"mecanismos el\u00e9ctricos Chaves sinalizadoras\" width=\"200\" height=\"200\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/a.jpg 200w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/a-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/a-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/a-140x140.jpg 140w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><a href=\"https:\/\/eriacomponentes.es\/comprar\/tecla-pulsador-luminoso\/\"><img decoding=\"async\" class=\"alignleft wp-image-14214\" title=\"mecanismos el\u00e9ctricos luz luminosa pulsar \u00edris s\u00e9rie bot\u00e3o luminoso\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-luz-luminoso-serie-iris-blanco-2.jpg\" alt=\"mecanismos el\u00e9ctricos luz luminosa pulsar \u00edris s\u00e9rie bot\u00e3o luminoso\" width=\"176\" height=\"176\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-luz-luminoso-serie-iris-blanco-2.jpg 200w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-luz-luminoso-serie-iris-blanco-2-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-luz-luminoso-serie-iris-blanco-2-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/tecla-pulsador-luz-luminoso-serie-iris-blanco-2-140x140.jpg 140w\" sizes=\"(max-width: 176px) 100vw, 176px\" \/><\/a><\/h2>\n<h2>Tomadas de computador e de dados<\/h2>\n<p>Os<strong> dados e as tomadas de computador<\/strong> s\u00e3o<strong> mecanismos<\/strong> muito necess\u00e1rios para qualquer casa, escrit\u00f3rio ou empresa nos dias de hoje.<\/p>\n<p>Na nossa sec\u00e7\u00e3o<strong> de mecanismos el\u00e9ctricos<\/strong> dispomos de uma vasta gama de<a href=\"https:\/\/eriacomponentes.es\/comprar-online\/mecanismos\/efapel-quadro-45\/tomas-informaticas\/\"> tomadas de computador e de dados<\/a> a pre\u00e7os muito competitivos.<\/p>\n<p><a href=\"https:\/\/eriacomponentes.es\/comprar\/modulo-conector-rj45-cat5e-stp-45988sbr\/\"><img decoding=\"async\" class=\"alignnone wp-image-14222\" title=\"m\u00f3dulo de liga\u00e7\u00e3o de mecanismos el\u00e9ctricos\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-rj45-efapel-300x300-1-300x300.jpg\" alt=\"m\u00f3dulo de liga\u00e7\u00e3o de mecanismos el\u00e9ctricos\" width=\"229\" height=\"229\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-rj45-efapel-300x300-1.jpg 300w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-rj45-efapel-300x300-1-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-rj45-efapel-300x300-1-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-rj45-efapel-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 229px) 100vw, 229px\" \/><\/a><a href=\"https:\/\/eriacomponentes.es\/comprar\/modulo-conector-coaxial-tf-45979-sbr\/\"><img decoding=\"async\" class=\"alignnone wp-image-14219\" title=\"m\u00f3dulo de liga\u00e7\u00e3o de mecanismos el\u00e9ctricos\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-coaxial-tipo-f-45979-sbr-efapel-300x300-1-300x300.jpg\" alt=\"m\u00f3dulo de liga\u00e7\u00e3o de mecanismos el\u00e9ctricos\" width=\"236\" height=\"236\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-coaxial-tipo-f-45979-sbr-efapel-300x300-1.jpg 300w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-coaxial-tipo-f-45979-sbr-efapel-300x300-1-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-coaxial-tipo-f-45979-sbr-efapel-300x300-1-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/modulo-conector-coaxial-tipo-f-45979-sbr-efapel-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>Tomadas de corrente<\/h2>\n<p>Temos uma <strong>sec\u00e7\u00e3o de <a href=\"https:\/\/eriacomponentes.es\/comprar-online\/mecanismos\/efapel-quadro-45\/bases-de-enchufes\/\">tomadas<\/a><\/strong> onde pode encontrar os diferentes modelos e escolher as que melhor se adaptam \u00e0s suas necessidades.<\/p>\n<p>Na nossa<strong> loja online de mecanismos el\u00e9ctricos<\/strong> fornecemos-lhe todos os <em>dados, fichas t\u00e9cnicas, possibilidades de<\/em> <em>instala\u00e7\u00e3o e diagramas de acabamentos<\/em> para facilitar tudo.<\/p>\n<p><a href=\"https:\/\/eriacomponentes.es\/comprar\/base-francesa-enclavamiento-45116-svm\/\"><img decoding=\"async\" class=\"alignnone wp-image-14220\" title=\"mecanismos el\u00e9ctricos Interbloqueio de base francesa\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-francesa-enclavamiento-45116-svm-quadro-45-efapel-300x300-1-300x300.jpg\" alt=\"mecanismos el\u00e9ctricos Interbloqueio de base francesa\" width=\"227\" height=\"227\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-francesa-enclavamiento-45116-svm-quadro-45-efapel-300x300-1.jpg 300w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-francesa-enclavamiento-45116-svm-quadro-45-efapel-300x300-1-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-francesa-enclavamiento-45116-svm-quadro-45-efapel-300x300-1-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-francesa-enclavamiento-45116-svm-quadro-45-efapel-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/><\/a><a href=\"https:\/\/eriacomponentes.es\/comprar\/base-triple-francesa-45195-sbr\/\"><img decoding=\"async\" class=\"alignnone wp-image-14221\" title=\"mecanismos el\u00e9ctricos de tripla base francesa\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-triple-francesa-quadro-45-efapel-300x300-1-300x300.jpg\" alt=\"mecanismos el\u00e9ctricos de tripla base francesa\" width=\"198\" height=\"198\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-triple-francesa-quadro-45-efapel-300x300-1.jpg 300w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-triple-francesa-quadro-45-efapel-300x300-1-150x150.jpg 150w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-triple-francesa-quadro-45-efapel-300x300-1-100x100.jpg 100w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/base-triple-francesa-quadro-45-efapel-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 198px) 100vw, 198px\" \/><\/a>           <img decoding=\"async\" class=\"alignnone wp-image-14223 size-medium\" title=\"Diagrama dos mecanismos el\u00e9ctricos acabados\" src=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/w-300x165.png\" alt=\"Diagrama dos mecanismos el\u00e9ctricos acabados\" width=\"300\" height=\"165\" srcset=\"https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/w-300x165.png 300w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/w-600x329.png 600w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/w-768x421.png 768w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/w-900x496.png 900w, https:\/\/eriacomponentes.es\/wp-content\/uploads\/2020\/12\/w.png 904w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h1><\/h1>\n<h2>A NOSSA EMPRESA<\/h2>\n<p>Na <strong>ERIA Componentes El\u00e9ctricos<\/strong> estamos dedicados \u00e0 venda e distribui\u00e7\u00e3o de <strong>produtos el\u00e9ctricos e<\/strong> <strong>industriais<\/strong> atrav\u00e9s do canal online. Temos um grupo de pessoas com grande experi\u00eancia no sector e que garantem aos nossos clientes o melhor tratamento poss\u00edvel. Como <strong>loja online<\/strong>, oferecemos aos nossos clientes pre\u00e7os muito atractivos e competitivos.<\/p>\n<p>Destacamo-nos na venda de <em>l\u00e2mpadas e tubos de LED, acumuladores de calor, mangueiras, pequenos materiais e mecanismos<\/em>, entre muitos outros artigos. As sec\u00e7\u00f5es mais valorizadas pelos clientes s\u00e3o <strong>ilumina\u00e7\u00e3o, dom\u00f3tica, disjuntores, fus\u00edveis, diferenciais, sistemas de fixa\u00e7\u00e3o, arm\u00e1rios e centraliza\u00e7\u00e3o de empresas de CGP<\/strong>.<\/p>\n<p>Temos mais de 20.000 refer\u00eancias em stock e trabalhamos com os principais fornecedores nacionais. Somos distribuidores de uma grande variedade de <strong>fabricantes de materiais el\u00e9ctricos<\/strong> tais como Efapel, Sylvania, Eaton, Delta Dore, Golmar, e muitos mais que pode ver no nosso cat\u00e1logo.<\/p>\n<p>Na <a href=\"https:\/\/eriacomponentes.es\/\">nossa loja online de componentes el\u00e9ctricos<\/a> pode escolher entre v\u00e1rios <strong>sistemas de pagamento:<\/strong> <em>cart\u00e3o de cr\u00e9dito, Paypal ou transfer\u00eancia banc\u00e1ria<\/em>, com o qual pode efectuar o pagamento das suas compras com total tranquilidade e confian\u00e7a, uma vez que temos todos os <strong>certificados de seguran\u00e7a<\/strong>.<\/p>\n<p>Acreditamos que<strong> a log\u00edstica<\/strong> \u00e9 tamb\u00e9m um aspecto importante que nos distingue dos nossos concorrentes. \u00c9 por isso que trabalhamos com v\u00e1rias ag\u00eancias para podermos adaptar-nos \u00e0s necessidades de cada cliente, para que possam receber os seus artigos o mais rapidamente poss\u00edvel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; Os mecanismos el\u00e9ctricos s\u00e3o um dos componentes essenciais em todos os tipos de casas e a sua escolha depende de muitos factores:&#8230;<\/p>\n","protected":false},"author":1296,"featured_media":33972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4110],"tags":[4111,4117,4112,4115,4114,4113,4118,4119,4120,4121,4116,4122],"class_list":{"0":"post-48379","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mecanismos-electricos-pt-pt","8":"tag-adaptadores-electricos-pt-pt","9":"tag-aquisicao-de-dados","10":"tag-botoes-electricos","11":"tag-chaves-de-iluminacao","12":"tag-componentes-electricos-pt-pt","13":"tag-dispositivos-electricos","14":"tag-iluminacao","15":"tag-instalacao-electrica","16":"tag-interruptores-electricos-pt-pt","17":"tag-interruptores-electricos-pt-pt-2","18":"tag-tomadas-de-computador","19":"tag-tomadas-de-corrente"},"_links":{"self":[{"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/posts\/48379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/users\/1296"}],"replies":[{"embeddable":true,"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=48379"}],"version-history":[{"count":0,"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/posts\/48379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/media\/33972"}],"wp:attachment":[{"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=48379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=48379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eriacomponentes.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=48379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}